{"id":20,"count":10,"description":"","link":"https:\/\/spavendome.fr\/en\/category\/soins-du-visage-beaute\/","name":"Facial care &amp; beauty","slug":"soins-du-visage-beaute","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/spavendome.fr\/en\/wp-json\/wp\/v2\/categories\/20","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spavendome.fr\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/spavendome.fr\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/spavendome.fr\/en\/wp-json\/wp\/v2\/posts?categories=20"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}