{"id":18,"count":5,"description":"","link":"https:\/\/spavendome.fr\/en\/category\/bien-etre-detente\/","name":"Wellness &amp; relaxation","slug":"bien-etre-detente","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/spavendome.fr\/en\/wp-json\/wp\/v2\/categories\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spavendome.fr\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/spavendome.fr\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/spavendome.fr\/en\/wp-json\/wp\/v2\/posts?categories=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}