{"id":285,"date":"2018-10-10T09:11:58","date_gmt":"2018-10-10T09:11:58","guid":{"rendered":"https:\/\/www.luno3284.odns.fr\/portfolio\/luke-in-the-house-of-jelly-radio-fenzes-10\/"},"modified":"2025-12-02T00:29:32","modified_gmt":"2025-12-01T23:29:32","slug":"luke-in-the-house-of-jelly-radio-fenzes-10","status":"publish","type":"blossom-portfolio","link":"https:\/\/spavendome.fr\/en\/portfolio\/luke-in-the-house-of-jelly-radio-fenzes-10\/","title":{"rendered":"Salle Head Spa - The exceptional hair experience."},"content":{"rendered":"<blockquote><p>D\u00e9couvrez notre salle Head Spa, un sanctuaire intime d\u00e9di\u00e9 au soin du cuir chevelu et \u00e0 la relaxation profonde.<\/p>\n<p>Sous la vo\u00fbte en pierre, l\u2019ambiance tamis\u00e9e et les lumi\u00e8res chaleureuses se m\u00ealent au parfum d\u00e9licat des bougies pour cr\u00e9er un v\u00e9ritable rituel immersif.<\/p>\n<p>La table de soin haut de gamme, les serviettes d\u00e9licatement pr\u00e9par\u00e9es et les gestes experts de nos praticiennes transforment chaque s\u00e9ance en un moment de pure renaissance : d\u00e9tente absolue, cuir chevelu revitalis\u00e9, cheveux sublim\u00e9s.<\/p>\n<p>Un espace o\u00f9 le luxe rencontre le bien-\u00eatre, et o\u00f9 chaque d\u00e9tail est pens\u00e9 pour vous offrir l\u2019exp\u00e9rience Head Spa la plus apaisante de Paris.<\/p><\/blockquote>","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez notre salle Head Spa, un sanctuaire intime d\u00e9di\u00e9 au soin du cuir chevelu et \u00e0 la relaxation profonde. Sous la vo\u00fbte en pierre, l\u2019ambiance tamis\u00e9e et les lumi\u00e8res chaleureuses &hellip; <\/p>","protected":false},"author":1,"featured_media":3798,"template":"","blossom_portfolio_categories":[30],"class_list":["post-285","blossom-portfolio","type-blossom-portfolio","status-publish","has-post-thumbnail","hentry","blossom_portfolio_categories-salon-de-beaute","latest_post"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/spavendome.fr\/en\/wp-json\/wp\/v2\/blossom-portfolio\/285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spavendome.fr\/en\/wp-json\/wp\/v2\/blossom-portfolio"}],"about":[{"href":"https:\/\/spavendome.fr\/en\/wp-json\/wp\/v2\/types\/blossom-portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/spavendome.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/spavendome.fr\/en\/wp-json\/wp\/v2\/blossom-portfolio\/285\/revisions"}],"predecessor-version":[{"id":3797,"href":"https:\/\/spavendome.fr\/en\/wp-json\/wp\/v2\/blossom-portfolio\/285\/revisions\/3797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spavendome.fr\/en\/wp-json\/wp\/v2\/media\/3798"}],"wp:attachment":[{"href":"https:\/\/spavendome.fr\/en\/wp-json\/wp\/v2\/media?parent=285"}],"wp:term":[{"taxonomy":"blossom_portfolio_categories","embeddable":true,"href":"https:\/\/spavendome.fr\/en\/wp-json\/wp\/v2\/blossom_portfolio_categories?post=285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}